{"id":16515,"date":"2023-01-18T13:47:09","date_gmt":"2023-01-18T13:47:09","guid":{"rendered":"https:\/\/protocoltoday.nl\/portfolio\/ponente-3\/"},"modified":"2024-03-01T15:41:07","modified_gmt":"2024-03-01T15:41:07","slug":"ponente-3","status":"publish","type":"portfolio","link":"https:\/\/protocoltoday.nl\/es\/portfolio\/ponente-3\/","title":{"rendered":"Cherin Jallis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16515\" class=\"elementor elementor-16515\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22d97aaa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22d97aaa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2c78196b\" data-id=\"2c78196b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1da065f9\" data-id=\"1da065f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7071c76b elementor-widget elementor-widget-text-editor\" data-id=\"7071c76b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span class=\"TextRun Highlight SCXW190254572 BCX8\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW190254572 BCX8\">Cherin Jallis<\/span><\/span><\/h1><h3>International recognition as an expert in etiquette.<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dda92f elementor-widget elementor-widget-image\" data-id=\"9dda92f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/elementor\/thumbs\/Cherin_Jallis_2_ProtocolToday-rieitbvh5fsuyh3xt2zu39qc5jpi1p7qee5oah9qz4.jpg\" title=\"Cherin_Jallis_2_ProtocolToday\" alt=\"Cherin_Jallis_2_ProtocolToday\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d80a08e elementor-widget elementor-widget-spacer\" data-id=\"d80a08e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-515057ea elementor-widget elementor-widget-text-editor\" data-id=\"515057ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW176271683 BCX8\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW176271683 BCX8\">Topic:<\/span><\/span><span class=\"TextRun SCXW176271683 BCX8\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW176271683 BCX8\"> <span class=\"TextRun SCXW102971751 BCX8\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW102971751 BCX8\">Protocol and etiquette: success in cross-cultural differences.<\/span><\/span><span class=\"EOP SCXW102971751 BCX8\" data-ccp-props=\"{&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/span><\/span><\/p><p>Biography: Cherin is certified in Luxury &amp; Lifestyle Management from Italy\u2019s Polimoda Institute of Fashion Design &amp; Marketing in Italy, and studied general etiquette and business protocol at Switzerland\u2019s Surval Institute in cooperation with the Institute Villa Pierrefeu. She is also a certified etiquette consultant in Canada after years of applying the finer points of social and business conduct.<\/p><p>Prior to this transition to etiquette training, Cherin spent ten years working in public relations. She coached clients one-on-one on their communication skills and approach to external parties.<\/p><p>She conducted several workshops, teaching various subjects but with her biggest passion being professional conduct \u2013 how to act and treat others.<\/p><p>Cherin also coordinated in-house corporate training on a range of personal skills. This included etiquette relating to communication, email writing, telephone correspondence, customer care, client relations and social events in all aspects. Her whole approach focused on the fundamental principles of grace and courtesy to elevate people\u2019s social and professional conduct.<\/p><p>UNITED ARAB EMIRATES<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5a9e0963\" data-id=\"5a9e0963\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d935e84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d935e84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80b3309\" data-id=\"80b3309\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69895c1c elementor-widget elementor-widget-spacer\" data-id=\"69895c1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-541e579c elementor-widget elementor-widget-text-editor\" data-id=\"541e579c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Otros Ponentes<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ecae1a elementor-grid-4 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"4ecae1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-34063 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-academia-masterclass-programs\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/organizaciones-internacionales\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg\" class=\"attachment-medium size-medium wp-image-34016\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/organizaciones-internacionales\/\" >\n\t\t\t\tORGANIZACIONES INTERNACIONALES\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/organizaciones-internacionales\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre ORGANIZACIONES INTERNACIONALES\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-34057 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-academia-masterclass-programs\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/universidades\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37550\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/universidades\/\" >\n\t\t\t\tUNIVERSIDADES\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/universidades\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre UNIVERSIDADES\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33112 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-servicios-home portfolio_category-servicios-protocoltoday\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-corporaciones\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37541\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-corporaciones\/\" >\n\t\t\t\tSERVICIOS PARA CORPORACIONES\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-corporaciones\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre SERVICIOS PARA CORPORACIONES\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33106 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-servicios-home portfolio_category-servicios-protocoltoday\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-embajadas\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo.jpg\" class=\"attachment-medium size-medium wp-image-38341\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-embajadas\/\" >\n\t\t\t\tSERVICIOS PARA EMBAJADAS\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-embajadas\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre SERVICIOS PARA EMBAJADAS\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33100 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-servicios-home portfolio_category-servicios-protocoltoday\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/membresia-global\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-300x300.jpg\" class=\"attachment-medium size-medium wp-image-32620\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-300x300.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-500x500.jpg 500w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-100x100.jpg 100w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5.jpg 525w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/membresia-global\/\" >\n\t\t\t\tMEMBRES\u00cdA GLOBAL\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/membresia-global\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre MEMBRES\u00cdA GLOBAL\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33094 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-academia-masterclass-programs\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/gobierno\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37517\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/gobierno\/\" >\n\t\t\t\tGOBIERNO\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/gobierno\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre GOBIERNO\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-221f7b51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"221f7b51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dfe7f45\" data-id=\"4dfe7f45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6be75b57 elementor-widget elementor-widget-spacer\" data-id=\"6be75b57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b8ee5a2 elementor-widget elementor-widget-text-editor\" data-id=\"3b8ee5a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Recommended VIP Interviews<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3596b0 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"7a3596b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.66000000000000003108624468950438313186168670654296875,&quot;sizes&quot;:[]},&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-38917 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categorizar tag-business-es tag-proffessionalism-es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/executive-certificate-program-in-modern-protocol-and-international-etiquette\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"147\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-300x147.jpg\" class=\"attachment-medium size-medium wp-image-39223\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-300x147.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-1024x503.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-768x378.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-600x295.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website.jpg 1068w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEXECUTIVE CERTIFICATE PROGRAM IN MODERN PROTOCOL AND INTERNATIONAL ETIQUETTE\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-35994 post type-post status-publish format-standard has-post-thumbnail hentry category-cultural-intelligence-es category-magazine-es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/protocol-and-business-culture-with-egyptians\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-300x94.png\" class=\"attachment-medium size-medium wp-image-38042\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-300x94.png 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-1024x320.png 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-768x240.png 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-1536x480.png 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-600x188.png 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday.png 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPROTOCOLO Y CULTURA DE NEGOCIOS CON EGIPCIOS\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-35965 post type-post status-publish format-standard hentry category-uncategorized\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/session-for-profesionals-in-protocol-and-etiquette\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSESI\u00d3N PARA PROFESIONALES EN PROTOCOLO Y ETIQUETA\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-34740 post type-post status-publish format-standard has-post-thumbnail hentry category-agenda2022_es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/executive-program-for-gobernment\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37517\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPROGRAMA EJECUTIVO PARA GOBIERNO\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-34771 post type-post status-publish format-standard has-post-thumbnail hentry category-agenda2022_es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/executive-program-for-international-organizations\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg\" class=\"attachment-medium size-medium wp-image-34016\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPROGRAMA EJECUTIVO PARA ORGANIZACIONES INTERNACIONALES\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-14648 post type-post status-publish format-standard has-post-thumbnail hentry category-agenda2022_es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/masterclass-etiqueta-internacional-gms-1\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-300x300.png\" class=\"attachment-medium size-medium wp-image-32282\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-300x300.png 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-150x150.png 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-100x100.png 100w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE.png 488w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMASTERCLASS ETIQUETA INTERNACIONAL (GMS-1)\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>International recognition as an expert in etiquette.<br \/>\nTopic: Protocol and etiquette: success in cross-cultural differences.<br \/>\nUNITED ARAB EMIRATES<\/p>\n","protected":false},"featured_media":21652,"parent":0,"menu_order":0,"template":"elementor_header_footer","categories":[],"tags":[],"portfolio_category":[136,110],"class_list":["post-16515","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-speaker-mujeres-como-embajadoras-culturales-iswca2024-es","portfolio_category-the-power-of-image-icpss-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cherin Jallis - Protocol Today<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cherin Jallis\" \/>\n<meta property=\"og:description\" content=\"International recognition as an expert in etiquette. Topic: Protocol and etiquette: success in cross-cultural differences. UNITED ARAB EMIRATES\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/\" \/>\n<meta property=\"og:site_name\" content=\"Protocol Today\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/protocoltodayacademy#\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T15:41:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/01\/Cherin_Jallis_2_ProtocolToday.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/\",\"name\":\"Cherin Jallis - Protocol Today\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cherin_Jallis_2_ProtocolToday.jpg\",\"datePublished\":\"2023-01-18T13:47:09+00:00\",\"dateModified\":\"2024-03-01T15:41:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cherin_Jallis_2_ProtocolToday.jpg\",\"contentUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cherin_Jallis_2_ProtocolToday.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/carmen-castillo-del-carpio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/protocoltoday.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cherin Jallis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#website\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/\",\"name\":\"Protocol Today\",\"description\":\"Protocol &amp; Soft diplomacy academy\",\"publisher\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#organization\"},\"alternateName\":\"Protocol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protocoltoday.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#organization\",\"name\":\"Protocol Today\",\"alternateName\":\"Protocol Academy\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/13.png\",\"contentUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/13.png\",\"width\":540,\"height\":540,\"caption\":\"Protocol Today\"},\"image\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/protocoltodayacademy#\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protocoltoday-consulting-academy\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/protocoltoday\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ProtocolToday\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cherin Jallis - Protocol Today","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/","og_locale":"es_ES","og_type":"article","og_title":"Cherin Jallis","og_description":"International recognition as an expert in etiquette. Topic: Protocol and etiquette: success in cross-cultural differences. UNITED ARAB EMIRATES","og_url":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/","og_site_name":"Protocol Today","article_publisher":"https:\/\/www.facebook.com\/protocoltodayacademy#","article_modified_time":"2024-03-01T15:41:07+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/01\/Cherin_Jallis_2_ProtocolToday.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/","url":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/","name":"Cherin Jallis - Protocol Today","isPartOf":{"@id":"https:\/\/protocoltoday.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/#primaryimage"},"image":{"@id":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/#primaryimage"},"thumbnailUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/01\/Cherin_Jallis_2_ProtocolToday.jpg","datePublished":"2023-01-18T13:47:09+00:00","dateModified":"2024-03-01T15:41:07+00:00","breadcrumb":{"@id":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/#primaryimage","url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/01\/Cherin_Jallis_2_ProtocolToday.jpg","contentUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/01\/Cherin_Jallis_2_ProtocolToday.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/protocoltoday.nl\/portfolio\/carmen-castillo-del-carpio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/protocoltoday.nl\/"},{"@type":"ListItem","position":2,"name":"Cherin Jallis"}]},{"@type":"WebSite","@id":"https:\/\/protocoltoday.nl\/#website","url":"https:\/\/protocoltoday.nl\/","name":"Protocol Today","description":"Protocol &amp; Soft diplomacy academy","publisher":{"@id":"https:\/\/protocoltoday.nl\/#organization"},"alternateName":"Protocol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protocoltoday.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/protocoltoday.nl\/#organization","name":"Protocol Today","alternateName":"Protocol Academy","url":"https:\/\/protocoltoday.nl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protocoltoday.nl\/#\/schema\/logo\/image\/","url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/10\/13.png","contentUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/10\/13.png","width":540,"height":540,"caption":"Protocol Today"},"image":{"@id":"https:\/\/protocoltoday.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/protocoltodayacademy#","https:\/\/www.linkedin.com\/company\/protocoltoday-consulting-academy\/?viewAsMember=true","https:\/\/www.instagram.com\/protocoltoday\/","https:\/\/www.youtube.com\/@ProtocolToday\/featured"]}]}},"_links":{"self":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio\/16515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":47,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio\/16515\/revisions"}],"predecessor-version":[{"id":25228,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio\/16515\/revisions\/25228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/media\/21652"}],"wp:attachment":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/media?parent=16515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/categories?post=16515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/tags?post=16515"},{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio_category?post=16515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}