{"id":28783,"date":"2024-12-10T08:38:02","date_gmt":"2024-12-10T08:38:02","guid":{"rendered":"https:\/\/protocoltoday.nl\/?post_type=portfolio&#038;p=28783"},"modified":"2025-04-10T11:49:15","modified_gmt":"2025-04-10T11:49:15","slug":"frans-scham","status":"publish","type":"portfolio","link":"https:\/\/protocoltoday.nl\/es\/portfolio\/frans-scham\/","title":{"rendered":"Frans Scham"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"28783\" class=\"elementor elementor-28783\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c5e3e83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c5e3e83\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8332af5\" data-id=\"8332af5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3e235385\" data-id=\"3e235385\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-115662ab elementor-widget elementor-widget-text-editor\" data-id=\"115662ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Frans Schram<\/h1><h3>Expert in International Negotiations\u00a0<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a2aa394 elementor-widget elementor-widget-image\" data-id=\"1a2aa394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/07\/Frans-Scharm-2-1.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45fa1567 elementor-widget elementor-widget-text-editor\" data-id=\"45fa1567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Topic: \u201cSame Table, Different Worlds: Navigating Culture in Global Negotiations\u201d<\/p><p>Frans Schram has over 15 years of experience in negotiation, mediation, intercultural dialogue, and diplomacy. As a trainer, facilitator, or coach, he regularly provides services to a wide range of public sector organisations (EU institutions, EU Presidencies, Foreign ministries, and international organisations), academic institutions, resistance\/liberation movements, NGOs, and private sector companies in more than 30 countries worldwide.<\/p><p>Frans holds a MA in Dutch, European and International Law from the University of Maastricht, the Universidad Aut\u00f3noma in Madrid and the Stellenbosch University in South Africa. He speaks fluent English, French, Spanish, German and Dutch (mother tongue).<\/p><p>GERMANY<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-48cf8b5f\" data-id=\"48cf8b5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-381c448e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"381c448e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2dbe72a0\" data-id=\"2dbe72a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a8aed9f elementor-widget elementor-widget-spacer\" data-id=\"3a8aed9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5736aa30 elementor-widget elementor-widget-text-editor\" data-id=\"5736aa30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>More Speakers<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a1764d1 elementor-grid-4 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"1a1764d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-34063 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-academia-masterclass-programs\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/organizaciones-internacionales\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg\" class=\"attachment-medium size-medium wp-image-34016\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/organizaciones-internacionales\/\" >\n\t\t\t\tORGANIZACIONES INTERNACIONALES\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/organizaciones-internacionales\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre ORGANIZACIONES INTERNACIONALES\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-34057 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-academia-masterclass-programs\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/universidades\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37550\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-students-protocoltoday-1.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/universidades\/\" >\n\t\t\t\tUNIVERSIDADES\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/universidades\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre UNIVERSIDADES\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33112 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-servicios-home portfolio_category-servicios-protocoltoday\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-corporaciones\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37541\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/corporate-protocoltoday.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-corporaciones\/\" >\n\t\t\t\tSERVICIOS PARA CORPORACIONES\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-corporaciones\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre SERVICIOS PARA CORPORACIONES\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33106 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-servicios-home portfolio_category-servicios-protocoltoday\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-embajadas\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo.jpg\" class=\"attachment-medium size-medium wp-image-38341\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/logo-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-embajadas\/\" >\n\t\t\t\tSERVICIOS PARA EMBAJADAS\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/servicios-para-embajadas\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre SERVICIOS PARA EMBAJADAS\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33100 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-servicios-home portfolio_category-servicios-protocoltoday\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/membresia-global\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-300x300.jpg\" class=\"attachment-medium size-medium wp-image-32620\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-300x300.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-500x500.jpg 500w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5-100x100.jpg 100w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-5.jpg 525w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/membresia-global\/\" >\n\t\t\t\tMEMBRES\u00cdA GLOBAL\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/membresia-global\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre MEMBRES\u00cdA GLOBAL\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-33094 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-academia-masterclass-programs\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/gobierno\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37517\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h6 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/gobierno\/\" >\n\t\t\t\tGOBIERNO\t\t\t<\/a>\n\t\t<\/h6>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/protocoltoday.nl\/es\/portfolio\/gobierno\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre GOBIERNO\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-576eec49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"576eec49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60b64f56\" data-id=\"60b64f56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41ce42e4 elementor-widget elementor-widget-spacer\" data-id=\"41ce42e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b3fbbc0 elementor-widget elementor-widget-text-editor\" data-id=\"3b3fbbc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Recommended VIP Interviews<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69db4375 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"69db4375\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.66000000000000003108624468950438313186168670654296875,&quot;sizes&quot;:[]},&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-38917 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categorizar tag-business-es tag-proffessionalism-es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/executive-certificate-program-in-modern-protocol-and-international-etiquette\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"147\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-300x147.jpg\" class=\"attachment-medium size-medium wp-image-39223\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-300x147.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-1024x503.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-768x378.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website-600x295.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/04\/banner-website.jpg 1068w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEXECUTIVE CERTIFICATE PROGRAM IN MODERN PROTOCOL AND INTERNATIONAL ETIQUETTE\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-35994 post type-post status-publish format-standard has-post-thumbnail hentry category-cultural-intelligence-es category-magazine-es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/protocol-and-business-culture-with-egyptians\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-300x94.png\" class=\"attachment-medium size-medium wp-image-38042\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-300x94.png 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-1024x320.png 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-768x240.png 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-1536x480.png 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday-600x188.png 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2026\/03\/protocoltoday.png 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPROTOCOLO Y CULTURA DE NEGOCIOS CON EGIPCIOS\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-35965 post type-post status-publish format-standard hentry category-uncategorized\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/session-for-profesionals-in-protocol-and-etiquette\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSESI\u00d3N PARA PROFESIONALES EN PROTOCOLO Y ETIQUETA\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-34740 post type-post status-publish format-standard has-post-thumbnail hentry category-agenda2022_es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/executive-program-for-gobernment\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg\" class=\"attachment-medium size-medium wp-image-37517\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-300x94.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1024x320.jpg 1024w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-768x240.jpg 768w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-1536x480.jpg 1536w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday-600x188.jpg 600w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/program-for-government-protocoltoday.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPROGRAMA EJECUTIVO PARA GOBIERNO\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-34771 post type-post status-publish format-standard has-post-thumbnail hentry category-agenda2022_es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/executive-program-for-international-organizations\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg\" class=\"attachment-medium size-medium wp-image-34016\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2025\/09\/cultural-2-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPROGRAMA EJECUTIVO PARA ORGANIZACIONES INTERNACIONALES\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-14648 post type-post status-publish format-standard has-post-thumbnail hentry category-agenda2022_es\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/protocoltoday.nl\/es\/masterclass-etiqueta-internacional-gms-1\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-300x300.png\" class=\"attachment-medium size-medium wp-image-32282\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-300x300.png 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-150x150.png 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE-100x100.png 100w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2023\/05\/300X300-WEBSITE.png 488w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMASTERCLASS ETIQUETA INTERNACIONAL (GMS-1)\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Expert in International Negotiation.<br \/>\nTopic: \u201cSame Table, Different Worlds: Navigating Culture in Global Negotiations\u201d.<br \/>\nGERMANY<\/p>\n","protected":false},"featured_media":29497,"parent":0,"menu_order":0,"template":"elementor_header_footer","categories":[],"tags":[],"portfolio_category":[168],"class_list":["post-28783","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-cultrual-intelligence-in-business-2025"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frans Scham - Protocol Today<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frans Scham\" \/>\n<meta property=\"og:description\" content=\"Expert in International Negotiation. Topic: \u201cSame Table, Different Worlds: Navigating Culture in Global Negotiations\u201d. GERMANY\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/\" \/>\n<meta property=\"og:site_name\" content=\"Protocol Today\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/protocoltodayacademy#\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T11:49:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/07\/Frans-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/\",\"name\":\"Frans Scham - Protocol Today\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Frans-.png\",\"datePublished\":\"2024-12-10T08:38:02+00:00\",\"dateModified\":\"2025-04-10T11:49:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Frans-.png\",\"contentUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Frans-.png\",\"width\":675,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/portfolio\\\/frans-scham\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/protocoltoday.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frans Scham\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#website\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/\",\"name\":\"Protocol Today\",\"description\":\"Protocol &amp; Soft diplomacy academy\",\"publisher\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#organization\"},\"alternateName\":\"Protocol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protocoltoday.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#organization\",\"name\":\"Protocol Today\",\"alternateName\":\"Protocol Academy\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/13.png\",\"contentUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/13.png\",\"width\":540,\"height\":540,\"caption\":\"Protocol Today\"},\"image\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/protocoltodayacademy#\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protocoltoday-consulting-academy\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/protocoltoday\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ProtocolToday\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frans Scham - Protocol Today","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/","og_locale":"es_ES","og_type":"article","og_title":"Frans Scham","og_description":"Expert in International Negotiation. Topic: \u201cSame Table, Different Worlds: Navigating Culture in Global Negotiations\u201d. GERMANY","og_url":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/","og_site_name":"Protocol Today","article_publisher":"https:\/\/www.facebook.com\/protocoltodayacademy#","article_modified_time":"2025-04-10T11:49:15+00:00","og_image":[{"width":675,"height":675,"url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/07\/Frans-.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/","url":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/","name":"Frans Scham - Protocol Today","isPartOf":{"@id":"https:\/\/protocoltoday.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/#primaryimage"},"image":{"@id":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/#primaryimage"},"thumbnailUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/07\/Frans-.png","datePublished":"2024-12-10T08:38:02+00:00","dateModified":"2025-04-10T11:49:15+00:00","breadcrumb":{"@id":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/#primaryimage","url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/07\/Frans-.png","contentUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/07\/Frans-.png","width":675,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/protocoltoday.nl\/portfolio\/frans-scham\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/protocoltoday.nl\/"},{"@type":"ListItem","position":2,"name":"Frans Scham"}]},{"@type":"WebSite","@id":"https:\/\/protocoltoday.nl\/#website","url":"https:\/\/protocoltoday.nl\/","name":"Protocol Today","description":"Protocol &amp; Soft diplomacy academy","publisher":{"@id":"https:\/\/protocoltoday.nl\/#organization"},"alternateName":"Protocol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protocoltoday.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/protocoltoday.nl\/#organization","name":"Protocol Today","alternateName":"Protocol Academy","url":"https:\/\/protocoltoday.nl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protocoltoday.nl\/#\/schema\/logo\/image\/","url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/10\/13.png","contentUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/10\/13.png","width":540,"height":540,"caption":"Protocol Today"},"image":{"@id":"https:\/\/protocoltoday.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/protocoltodayacademy#","https:\/\/www.linkedin.com\/company\/protocoltoday-consulting-academy\/?viewAsMember=true","https:\/\/www.instagram.com\/protocoltoday\/","https:\/\/www.youtube.com\/@ProtocolToday\/featured"]}]}},"_links":{"self":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio\/28783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":10,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio\/28783\/revisions"}],"predecessor-version":[{"id":30619,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio\/28783\/revisions\/30619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/media\/29497"}],"wp:attachment":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/media?parent=28783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/categories?post=28783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/tags?post=28783"},{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/portfolio_category?post=28783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}