{"id":8507,"date":"2022-03-30T14:42:06","date_gmt":"2022-03-30T14:42:06","guid":{"rendered":"https:\/\/protocoltoday.nl\/?p=8507"},"modified":"2023-05-19T11:43:56","modified_gmt":"2023-05-19T11:43:56","slug":"reflexiones-y-tips-de-buen-comportamientos","status":"publish","type":"post","link":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/","title":{"rendered":"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8507\" class=\"elementor elementor-8507\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56dfefb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56dfefb0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-35806e34\" data-id=\"35806e34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26be13a7 elementor-widget elementor-widget-text-editor\" data-id=\"26be13a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Con frecuencia escuchamos, en personas de variadas edades y actividades, unas cuantas de las siguientes frases para pretender justificar sus deficientes modales: \u201cyo soy as\u00ed\u201d, \u201cestoy estresado\u201d, \u201cas\u00ed me pongo en momentos de tensi\u00f3n\u201d, \u201cque no se metan conmigo\u201d, \u201cla etiqueta social son cosas del pasado\u201d, etc. Podr\u00eda continuar formulando un listado de las aseveraciones empleadas.<\/strong><\/p><p>Sin embargo, debo subrayar lo que, al parecer, desconocen o reh\u00fayen analizar m\u00faltiples hombres y mujeres. El comportamiento trasluce la vigencia del respeto, la tolerancia y el di\u00e1logo; fortalece la disposici\u00f3n del lazo humano y, por lo tanto, de la convivencia; realza la personalidad; fomenta una percepci\u00f3n favorable; enaltece el perfil profesional y constituye una excelente carta de presentaci\u00f3n.<\/p><p>\u00bfPor qu\u00e9 es dif\u00edcil observar una correcta actuaci\u00f3n? \u00a0Son abundantes las motivaciones que influyen en el cada vez m\u00e1s deteriorado y lacerante clima de coexistencia colectiva. Factores como las habilidades blandas, la educaci\u00f3n, la cultural, el entorno, entre otros, explican -m\u00e1s no apoyar- lo acontecido.<\/p><p>A mi parecer, es incongruente continuar inmensos en la \u201czona de confort\u201d -cruzados de brazos, distantes e indolentes- y desde all\u00ed cuestionar esta dram\u00e1tica realidad que afecta el bienestar, la salud emocional, la armon\u00eda y el discernimiento entre seres pensantes. Debemos actuar; s\u00ed, debemos actuar en nuestro campo de desenvolvimiento.<\/p><p>En tal sentido, comparto concisos y espec\u00edficos aportes enfocados a lograr una conducta acertada. No se requiere recurrir a un \u201cmanual\u201d o \u201ccurso\u201d de etiqueta social, tampoco pretender conducirse de forma r\u00edgida, inflexible y superficial. Solamente se exhorta utilizar el criterio, el sentido com\u00fan y la convicci\u00f3n de adjudicarnos una papel diferente, cualitativo y positivo encaminado a una saludable conexi\u00f3n entre hombres y mujeres. <strong>\u00a1Empecemos!<\/strong><\/p><p><em><strong>Puntualidad.<\/strong><\/em> Aplicar esta regla de oro es sin\u00f3nimo de finura, organizaci\u00f3n y disciplina. Sugiero emplear los medios tecnol\u00f3gicos y, especialmente, su celular para calcular tiempos, distancias, tr\u00e1fico vehicular y convertirla en una cultura particular. Su pr\u00e1ctica puede beneficiarlo en el quehacer corporativo y, por cierto, genera atenci\u00f3n y seguridad.<\/p><p><em><strong>Saludo.<\/strong><\/em> Es el primer suceso establecido en la correlaci\u00f3n humana -por ef\u00edmera que sea- y, adem\u00e1s, describe la inteligencia interpersonal. Tenga en cuenta: mire a los ojos, sonr\u00eda, extienda la mano con seguridad (seg\u00fan el caso) y trasmita un mensaje oral agradable. Son pautas altamente propicias para generar una afable impresi\u00f3n. H\u00e1galo con un adem\u00e1n c\u00e1lido que refleje su educaci\u00f3n. El caballero deber\u00e1 inh\u00edbase de jalar el brazo de la dama para darle un \u201cbeso\u201d en la mejilla que \u00e9sta no ha autorizado. Conozco un sinf\u00edn de caballeros, incluyendo maestros de ceremonias y asesores en protocolo y afines, con esa inc\u00f3moda e irrespetuosa man\u00eda.<\/p><p><em><strong>Discreci\u00f3n.<\/strong><\/em> Renuncie a la pegajosa costumbre de formular preguntas o comentarios personales. Son lamentables las habladur\u00edas acerca de pormenores sentimentales, enfermedades, desgracias y averiguaciones privadas. Guardar silencio es inherente en un ser mesurado y una haza\u00f1a en una comunidad inelegante e impertinente. Asumir un talante reservado inspira confianza. No olvide: \u201cLa prudencia se detiene, donde la ignorancia ingresa\u201d.<\/p><p><em><strong>Autocontrol.<\/strong><\/em> Es imperativo ocuparnos de la empat\u00eda y la afamada inteligencia emocional con el prop\u00f3sito de controlar reacciones inadecuadas; muestre madurez, ponderaci\u00f3n y equilibrio. Lecturas, capacitaciones y ciertas actividades contribuyen a desarrollar esta capacidad impostergable en per\u00edodos de aguda confrontaci\u00f3n y desencuentros. Evite impulsos acalorados, subidos de tono y agresivos: administre sus intransigencias.<\/p><p><em><strong>Celular.<\/strong><\/em> Es una herramienta de comunicaci\u00f3n importante, no un juguete para lucir en p\u00fablico. Jam\u00e1s se pone en la mesa como cubierto; p\u00f3ngalo en silencio en lugares cerrados; obvie contestar sin antes pedir permiso y retirarse; \u00faselo con cautela. Abst\u00e9ngase de atender sus redes sociales mientras sostiene una conversaci\u00f3n, se interpretar\u00e1 como un gesto de descortes\u00eda. Miro esta censurable rutina en autodenominados \u201cexpertos\u201d en urbanidad desesperados por atender a la supuesta novia. Reb\u00e9lese ante la actual inopia y resignaci\u00f3n masiva que enfrentamos.<\/p><p><em><strong>Dejar en visto<\/strong><\/em>. De este germen nadie se salva. Es un mal que se caracteriza por su r\u00e1pida y masiva propalaci\u00f3n en \u00e9pocas de apremios e indelicadezas. Podr\u00eda resolverse a partir de transparentar los instantes en que est\u00e1 enlazado con los medios virtuales; eluda colocar todo el tiempo \u201cconectado\u201d. As\u00ed informa los momentos de disponibilidad. Responda con inmediatez dentro de las siguientes 24 horas.<\/p><p><em><strong>Imagen personal<\/strong><\/em>. Es una afirmaci\u00f3n de autovaloraci\u00f3n y consideraci\u00f3n: cuide su vestimenta, aseo y arreglo individual. La apariencia y el atuendo retratan su estado an\u00edmico; son c\u00f3digos significativos de su concepto de s\u00ed mismo. Puede ser determinante para abrirle o cerrarle puertas en su conexi\u00f3n empresarial. Esto me trae a la memoria a un fingido \u201cespecialista\u201d protocolar que acude en buzo a trabajar a una empresa consagrada a la planificaci\u00f3n de graduaciones universitarias.<\/p><p><em><strong>Consumo de alimentos<\/strong><\/em>. Su actuaci\u00f3n lo expone m\u00e1s de lo imaginado. Prescinda sentarse cuando est\u00e9 aquejado por una enfermedad; realice un saludo general cuando los invitados est\u00e1n en sus asientos; esquive interrogar al que declina beber o saborear algo de lo ofrecido; entable charlas atractivas; no se retire al menos que sea urgente; el anfitri\u00f3n es el primero en comenzar a comer; los asistentes se ubicar\u00e1n en los sitios indicados por quien preside el encuentro, no pretenda hacerlo junto a quien usted desea como intentan seres con pobres habilidades sociales y exiguo mundo. Aconsejo portarse con tino.<\/p><p><strong><em>Visitas<\/em><\/strong>. Nunca se hacen, incluso a allegados de confianza, sin antes anunciarse mediante una llamada telef\u00f3nica o por alg\u00fan otro medio; menos en las horas de los alimentos. Si es un suceso urgente permanezca el tiempo atinado y sortee poner en aprietos a los due\u00f1os de casa. Eso me recuerda a familiares y amigos -pr\u00f3ximos a mi domicilio- que durante muchos a\u00f1os han incomodado, a mis padres y a m\u00ed, con su improperio y distorsionada interpretaci\u00f3n del estrecho v\u00ednculo existente. Todav\u00eda debo enfrentar en ciertas coyunturas esta desprovista manifestaci\u00f3n de educaci\u00f3n y sensatez.<\/p><p><em><strong>\u201cGracias\u201d y \u201cPor favor\u201d<\/strong><\/em>. Son expresiones de elevada performance. Es poco usual; no obstante, esta espont\u00e1nea y sincera usanza lo diferenciar\u00e1 en tan fecundo oc\u00e9ano de agrestes costumbres. Constituyen t\u00e9rminos seductores, expl\u00edcitos de su \u00f3ptima formaci\u00f3n y hacen grata nuestra alternancia. Comience a usarlos en su di\u00e1logo cotidiano.<\/p><p><em><strong>Valores<\/strong><\/em>. Componen una gu\u00eda orientadora de nuestras obras en la vida. Poseer una s\u00f3lida estructura moral definida, entre otros, por la solidaridad, la honradez, la lealtad y la tolerancia, enaltecen la conducta. Aconsejo interiorizarlos con coherencia, dignidad y convertirlos en una de las columnas que prescriba sus actos e inspire su porvenir.<\/p><p>Aprendamos a sostener un trato rec\u00edproco sin distinci\u00f3n de estatus, estados an\u00edmicos, jerarqu\u00edas, edades o procedencias. De all\u00ed que, reitero, ello implica un m\u00ednimo de amplitud cr\u00edtica y reflexiva para eludir reclamar lo que soslayamos dar al semejante. Seamos equitativos, justos y mutuos. Atesoremos como preponderante objetivo \u201chumanizar\u201d el espacio en el que interactuamos\u2026\u00bfQu\u00e9 opina?<\/p><p>Probablemente este prop\u00f3sito exige renunciar a esa postura ego\u00edsta, ap\u00e1tica, fr\u00edvola e insensible. \u00bfQu\u00e9 le parece si comenzamos a corresponder al pr\u00f3jimo como desear\u00edamos ser tratados? \u00bfNo ser\u00eda un gesto de nobleza y justicia? En cada uno de nosotros est\u00e1 el hermoso, imperioso e impostergable desaf\u00edo de erigir una mejor sociedad. Todos estamos obligados a demostrar genuina entrega, dimensi\u00f3n humana y probados principios. \u00a1Pi\u00e9nselo!\u00a0 <a href=\"http:\/\/wperezruiz.blogspot.com\/\">http:\/\/wperezruiz.blogspot.com\/<\/a><\/p><p><a href=\"https:\/\/protocoltoday.nl\/es\/vip-magazine-edicion-especial\/\">VIP EDICI\u00d3N ESPECIAL<\/a><\/p><p><a href=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/11\/BuildUp-Advertisements-Informative-Es.pdf\">PROMUEVA SU EMPRESA INTERNACIONALMENTE EN MAGAZINE MENTALIDAD GLOBAL<\/a><\/p><p><a href=\"https:\/\/protocoltoday.nl\/es\/academy\/\">PROTOCOLTODAY ACADEMIA DE PROTOCOLO &amp; DIPLOMACIA<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5b30565d\" data-id=\"5b30565d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-386e38bd elementor-share-buttons--color-custom elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-global elementor-global-5996 elementor-widget-share-buttons\" data-id=\"386e38bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11d4b7a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11d4b7a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-879dd33\" data-id=\"879dd33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b86957b elementor-widget elementor-widget-image\" data-id=\"7b86957b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Wilfredo_Perez_Ruiz_ProtocolToday-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4749\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Wilfredo_Perez_Ruiz_ProtocolToday-150x150.jpg 150w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Wilfredo_Perez_Ruiz_ProtocolToday-e1701769610166-100x100.jpg 100w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Wilfredo_Perez_Ruiz_ProtocolToday-300x300.jpg 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Wilfredo_Perez_Ruiz_ProtocolToday-e1701769610166.jpg 200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2cbad9ff\" data-id=\"2cbad9ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44bbf0d9 elementor-widget elementor-widget-text-editor\" data-id=\"44bbf0d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Redactado por Wilfredo P\u00e9rez Ruiz, Docente, comunicador y consultor en protocolo, ceremonial, etiqueta social y relaciones pu\u0301blicas, escritor y co-editor de Maganine Mentalidad Global.<\/h3><h3>30 de Marzo 2022, Per\u00fa\u00a0<\/h3><h3>Categor\u00eda: Etiqueta\u00a0<\/h3><h3>Referencia: WP30032022EP<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73847fa1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73847fa1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5713a027\" data-id=\"5713a027\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a6fb588 elementor-widget elementor-widget-image\" data-id=\"3a6fb588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"156\" src=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Protocol-Today-MAGAZINE-W@3x-300x156.png\" class=\"attachment-medium size-medium wp-image-4413\" alt=\"\" srcset=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Protocol-Today-MAGAZINE-W@3x-300x156.png 300w, https:\/\/protocoltoday.nl\/wp-content\/uploads\/2021\/07\/Protocol-Today-MAGAZINE-W@3x.png 469w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5cc3aed8\" data-id=\"5cc3aed8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca5f154 elementor-widget elementor-widget-spacer\" data-id=\"3ca5f154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17a43e75 elementor-widget elementor-widget-text-editor\" data-id=\"17a43e75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>\u201cSomos una empresa de desarrollo de capacidades que conecta valores, culturas, organizaciones, individuos y sociedades en todo el mundo\u201d<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d49b21 elementor-widget elementor-widget-spacer\" data-id=\"16d49b21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Con frecuencia escuchamos, en personas de variadas edades y actividades, unas cuantas de las siguientes frases para pretender justificar sus deficientes modales: \u201cyo soy as\u00ed\u201d, \u201cestoy estresado\u201d, \u201cas\u00ed me pongo en momentos de tensi\u00f3n\u201d, \u201cque no se metan conmigo\u201d, \u201cla etiqueta social son cosas del pasado\u201d, etc. Podr\u00eda continuar formulando un listado de las aseveraciones [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":8817,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"page_builder":"","footnotes":""},"categories":[62,60],"tags":[],"class_list":["post-8507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etiqueta-de-negocios","category-magazine-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO - Protocol Today<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO\" \/>\n<meta property=\"og:description\" content=\"Con frecuencia escuchamos, en personas de variadas edades y actividades, unas cuantas de las siguientes frases para pretender justificar sus deficientes modales: \u201cyo soy as\u00ed\u201d, \u201cestoy estresado\u201d, \u201cas\u00ed me pongo en momentos de tensi\u00f3n\u201d, \u201cque no se metan conmigo\u201d, \u201cla etiqueta social son cosas del pasado\u201d, etc. Podr\u00eda continuar formulando un listado de las aseveraciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/\" \/>\n<meta property=\"og:site_name\" content=\"Protocol Today\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/protocoltodayacademy#\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T14:42:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-19T11:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2022\/04\/Afbeelding1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"513\" \/>\n\t<meta property=\"og:image:height\" content=\"343\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/\"},\"author\":{\"name\":\"Adriana\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/person\\\/86246590b4cc235753dd825429f36927\"},\"headline\":\"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO\",\"datePublished\":\"2022-03-30T14:42:06+00:00\",\"dateModified\":\"2023-05-19T11:43:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/\"},\"wordCount\":1358,\"publisher\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Afbeelding1.jpg\",\"articleSection\":[\"Etiqueta de Negocios\",\"Magazine\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/\",\"name\":\"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO - Protocol Today\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Afbeelding1.jpg\",\"datePublished\":\"2022-03-30T14:42:06+00:00\",\"dateModified\":\"2023-05-19T11:43:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Afbeelding1.jpg\",\"contentUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Afbeelding1.jpg\",\"width\":513,\"height\":343},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/reflexiones-y-tips-de-buen-comportamientos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/protocoltoday.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#website\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/\",\"name\":\"Protocol Today\",\"description\":\"Protocol &amp; Soft diplomacy academy\",\"publisher\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#organization\"},\"alternateName\":\"Protocol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protocoltoday.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#organization\",\"name\":\"Protocol Today\",\"alternateName\":\"Protocol Academy\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/13.png\",\"contentUrl\":\"https:\\\/\\\/protocoltoday.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/13.png\",\"width\":540,\"height\":540,\"caption\":\"Protocol Today\"},\"image\":{\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/protocoltodayacademy#\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/protocoltoday-consulting-academy\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/protocoltoday\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ProtocolToday\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/protocoltoday.nl\\\/#\\\/schema\\\/person\\\/86246590b4cc235753dd825429f36927\",\"name\":\"Adriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60314a6fbf7701ecb911e5efdb21c4ffbf54dd95e1818a90e87fecd37f1fbf55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60314a6fbf7701ecb911e5efdb21c4ffbf54dd95e1818a90e87fecd37f1fbf55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60314a6fbf7701ecb911e5efdb21c4ffbf54dd95e1818a90e87fecd37f1fbf55?s=96&d=mm&r=g\",\"caption\":\"Adriana\"},\"url\":\"https:\\\/\\\/protocoltoday.nl\\\/es\\\/author\\\/adriana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO - Protocol Today","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/","og_locale":"es_ES","og_type":"article","og_title":"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO","og_description":"Con frecuencia escuchamos, en personas de variadas edades y actividades, unas cuantas de las siguientes frases para pretender justificar sus deficientes modales: \u201cyo soy as\u00ed\u201d, \u201cestoy estresado\u201d, \u201cas\u00ed me pongo en momentos de tensi\u00f3n\u201d, \u201cque no se metan conmigo\u201d, \u201cla etiqueta social son cosas del pasado\u201d, etc. Podr\u00eda continuar formulando un listado de las aseveraciones [&hellip;]","og_url":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/","og_site_name":"Protocol Today","article_publisher":"https:\/\/www.facebook.com\/protocoltodayacademy#","article_published_time":"2022-03-30T14:42:06+00:00","article_modified_time":"2023-05-19T11:43:56+00:00","og_image":[{"width":513,"height":343,"url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2022\/04\/Afbeelding1.jpg","type":"image\/jpeg"}],"author":"Adriana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Adriana","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/#article","isPartOf":{"@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/"},"author":{"name":"Adriana","@id":"https:\/\/protocoltoday.nl\/#\/schema\/person\/86246590b4cc235753dd825429f36927"},"headline":"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO","datePublished":"2022-03-30T14:42:06+00:00","dateModified":"2023-05-19T11:43:56+00:00","mainEntityOfPage":{"@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/"},"wordCount":1358,"publisher":{"@id":"https:\/\/protocoltoday.nl\/#organization"},"image":{"@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/#primaryimage"},"thumbnailUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2022\/04\/Afbeelding1.jpg","articleSection":["Etiqueta de Negocios","Magazine"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/","url":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/","name":"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO - Protocol Today","isPartOf":{"@id":"https:\/\/protocoltoday.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/#primaryimage"},"image":{"@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/#primaryimage"},"thumbnailUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2022\/04\/Afbeelding1.jpg","datePublished":"2022-03-30T14:42:06+00:00","dateModified":"2023-05-19T11:43:56+00:00","breadcrumb":{"@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/#primaryimage","url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2022\/04\/Afbeelding1.jpg","contentUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2022\/04\/Afbeelding1.jpg","width":513,"height":343},{"@type":"BreadcrumbList","@id":"https:\/\/protocoltoday.nl\/es\/reflexiones-y-tips-de-buen-comportamientos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/protocoltoday.nl\/"},{"@type":"ListItem","position":2,"name":"REFLEXIONES Y TIPS DE BUEN COMPORTAMIENTO"}]},{"@type":"WebSite","@id":"https:\/\/protocoltoday.nl\/#website","url":"https:\/\/protocoltoday.nl\/","name":"Protocol Today","description":"Protocol &amp; Soft diplomacy academy","publisher":{"@id":"https:\/\/protocoltoday.nl\/#organization"},"alternateName":"Protocol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protocoltoday.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/protocoltoday.nl\/#organization","name":"Protocol Today","alternateName":"Protocol Academy","url":"https:\/\/protocoltoday.nl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/protocoltoday.nl\/#\/schema\/logo\/image\/","url":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/10\/13.png","contentUrl":"https:\/\/protocoltoday.nl\/wp-content\/uploads\/2024\/10\/13.png","width":540,"height":540,"caption":"Protocol Today"},"image":{"@id":"https:\/\/protocoltoday.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/protocoltodayacademy#","https:\/\/www.linkedin.com\/company\/protocoltoday-consulting-academy\/?viewAsMember=true","https:\/\/www.instagram.com\/protocoltoday\/","https:\/\/www.youtube.com\/@ProtocolToday\/featured"]},{"@type":"Person","@id":"https:\/\/protocoltoday.nl\/#\/schema\/person\/86246590b4cc235753dd825429f36927","name":"Adriana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/60314a6fbf7701ecb911e5efdb21c4ffbf54dd95e1818a90e87fecd37f1fbf55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/60314a6fbf7701ecb911e5efdb21c4ffbf54dd95e1818a90e87fecd37f1fbf55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60314a6fbf7701ecb911e5efdb21c4ffbf54dd95e1818a90e87fecd37f1fbf55?s=96&d=mm&r=g","caption":"Adriana"},"url":"https:\/\/protocoltoday.nl\/es\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/posts\/8507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/comments?post=8507"}],"version-history":[{"count":16,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/posts\/8507\/revisions"}],"predecessor-version":[{"id":19438,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/posts\/8507\/revisions\/19438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/media\/8817"}],"wp:attachment":[{"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/media?parent=8507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/categories?post=8507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protocoltoday.nl\/es\/wp-json\/wp\/v2\/tags?post=8507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}